{"id":300,"date":"2018-06-22T09:14:44","date_gmt":"2018-06-22T09:14:44","guid":{"rendered":"http:\/\/www.mydentalmexico.com\/?p=300"},"modified":"2018-06-22T09:14:44","modified_gmt":"2018-06-22T09:14:44","slug":"los-implantes-dentales-son-aptos-para-todo-el-mundo","status":"publish","type":"post","link":"https:\/\/www.mydentalmexico.com\/index.php\/2018\/06\/22\/los-implantes-dentales-son-aptos-para-todo-el-mundo\/","title":{"rendered":"\u00bfLos implantes dentales son aptos para todo el mundo?"},"content":{"rendered":"<p>Sin duda los implantes dentales son la mejor soluci\u00f3n para devolver y recuperar la mejor sonrisa de nuestros pacientes, mediante rehabilitaciones id\u00e9nticas a su diente natural, sin limitarnos solamente en la funcionalidad, sino teniendo tambi\u00e9n en cuenta la est\u00e9tica y la naturalidad.<\/p>\n<p>Los <a href=\"https:\/\/es.wikipedia.org\/wiki\/Implante_dental\">implantes<\/a> son sin\u00f3nimo de una elevada tasa de \u00e9xito y duraci\u00f3n prolongada, es un tratamiento muy satisfactorio e incluso puede aplicarse en casos m\u00e1s complejos gracias a los m\u00e9todos m\u00e1s avanzados de MaxiloDexeus.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.clinicadrarias.es\/wp-content\/uploads\/2016\/09\/implante-dental-gijon.jpg\" alt=\"implante dental\" width=\"550\" \/><\/p>\n<p>\u00bfLos implantes dentales son aptos para todo el mundo?<br \/>\nLa colocaci\u00f3n de implantes dentales es uno de los tratamientos m\u00e1s demandados en mi cl\u00ednica, personas de todo tipo de edades y caracter\u00edsticas acuden a preguntarme por su caso en concreto pero, existen unos factores de riesgo a la hora de contemplar la rehabilitaci\u00f3n de la sonrisa con implantes.<\/p>\n<p>Implantes dentales con la enfermedad periodontal<br \/>\nLa enfermedad periodontal en un pacientes afecta a la colocaci\u00f3n de los implantes dentales por dos motivos:<\/p>\n<p>La similitud entre la microfibra que coloniza los dientes y la que coloniza los implantes.<br \/>\nLa existencia de un fenotipo hiperinflamatorio.<br \/>\nLa periodontitis influye en la calidad del hueso, en la altura y en la dimensi\u00f3n buco-lingual, que son muy importantes para la colocaci\u00f3n de los implantes dentales en la localizaci\u00f3n deseada.<\/p>\n<p>Por lo tanto, este tipo de paciente deber\u00e1 realizar un tratamiento y mantenimiento periodontal para que la colocaci\u00f3n del implante dental no suponga ning\u00fan riesgo. En este tipo de pacientes seremos m\u00e1s estrictos en el mantemiento y vigilancia de la aparici\u00f3n de perimplantitis.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sin duda los implantes dentales son la mejor soluci\u00f3n para devolver y recuperar la mejor sonrisa de nuestros pacientes, mediante rehabilitaciones id\u00e9nticas a su diente natural, sin limitarnos solamente en la funcionalidad, sino teniendo tambi\u00e9n en cuenta la est\u00e9tica y la naturalidad. Los implantes son sin\u00f3nimo de una elevada tasa de \u00e9xito y duraci\u00f3n prolongada, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-300","post","type-post","status-publish","format-standard","hentry","category-implantes-dentales"],"_links":{"self":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts\/300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=300"}],"version-history":[{"count":1,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts\/300\/revisions"}],"predecessor-version":[{"id":301,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts\/300\/revisions\/301"}],"wp:attachment":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}