{"id":255,"date":"2018-02-14T09:56:15","date_gmt":"2018-02-14T09:56:15","guid":{"rendered":"http:\/\/www.mydentalmexico.com\/?p=255"},"modified":"2018-02-12T10:01:32","modified_gmt":"2018-02-12T10:01:32","slug":"cuales-pueden-ser-los-efectos-secundarios-a-la-colocacion-de-implantes-dentales","status":"publish","type":"post","link":"https:\/\/www.mydentalmexico.com\/index.php\/2018\/02\/14\/cuales-pueden-ser-los-efectos-secundarios-a-la-colocacion-de-implantes-dentales\/","title":{"rendered":"\u00bfCu\u00e1les pueden ser los efectos secundarios a la colocaci\u00f3n de implantes dentales?"},"content":{"rendered":"<p>La p\u00e9rdida dental puede suponer un problema en la boca ya que la funci\u00f3n masticatoria se ve afectada. En muchos de estos casos, se opta para colocar implantes dentales para restituir la funci\u00f3n bucodental.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/estudidentalbarcelona.com\/wp-content\/uploads\/2017\/12\/efectos-secundarios-de-los-implantes-dentales.jpg?fit=900%2C500&amp;ssl=1\" \/><\/p>\n<p>La colocaci\u00f3n de los implantes dentales es un procedimiento que se realiza de forma quir\u00fargica. El acto quir\u00fargico puede favorecer la aparici\u00f3n de efectos secundarios que en muchas ocasiones suelen cursar con normalidad.<\/p>\n<p>El edema o la hinchaz\u00f3n suelen ser los principales efectos secundarios tras la colocaci\u00f3n de los implantes dentales. En el postoperatorio temprano, hay un edema el cual puede controlarse mediante la aplicaci\u00f3n de hielo de forma intermitente en la zona y mediante antiinflamatorios.<\/p>\n<p>Tambi\u00e9n pueden aparecer eritemas, llamados moratones. Se trata de respuestas normales que el cuerpo hace tras la intervenci\u00f3n quir\u00fargica. Junto a esto, el dolor o sensaci\u00f3n dolorosa suele ser frecuente. Gracias a los f\u00e1rmacos analg\u00e9sicos, el dolor puede ser controlado.<\/p>\n<p>Otro de los efectos secundarios puede ser la infecci\u00f3n de la zona. Es conveniente realizar una buena higiene oral y seguir las pautas indicadas por el especialista para que los efectos secundarios sean los m\u00ednimos y que el postoperatorio curse con normalidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La p\u00e9rdida dental puede suponer un problema en la boca ya que la funci\u00f3n masticatoria se ve afectada. En muchos de estos casos, se opta para colocar implantes dentales para restituir la funci\u00f3n bucodental. La colocaci\u00f3n de los implantes dentales es un procedimiento que se realiza de forma quir\u00fargica. El acto quir\u00fargico puede favorecer la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-255","post","type-post","status-publish","format-standard","hentry","category-implantes-dentales"],"_links":{"self":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts\/255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=255"}],"version-history":[{"count":1,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts\/255\/revisions"}],"predecessor-version":[{"id":256,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts\/255\/revisions\/256"}],"wp:attachment":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}