{"id":214,"date":"2017-11-11T03:48:30","date_gmt":"2017-11-11T03:48:30","guid":{"rendered":"http:\/\/www.mydentalmexico.com\/?p=214"},"modified":"2017-11-11T03:51:34","modified_gmt":"2017-11-11T03:51:34","slug":"esterilizar-la-pieza-de-mano-es-asegurar-su-futuro","status":"publish","type":"post","link":"https:\/\/www.mydentalmexico.com\/index.php\/2017\/11\/11\/esterilizar-la-pieza-de-mano-es-asegurar-su-futuro\/","title":{"rendered":"Esterilizar la pieza de mano dental es asegurar su futuro"},"content":{"rendered":"<p>Uno de los mayores expertos internacionales en seguridad del paciente y control de infecciones asegura convincentemente que no esterilizar la pieza de mano es una conducta de alto riesgo para la salud de nuestros pacientes y para nuestra carrera profesional.<\/p>\n<p>Las autoridades sanitarias, las instituciones acad\u00e9micas y muchos dentistas han pasado por alto durante a\u00f1os algo inaudito: que la pieza de mano no se lavase antes de introducirse en la boca del siguiente paciente.<\/p>\n<p>Lo cierto es que todo paciente debe ser atendido con instrumental est\u00e9ril, ya que los <a href=\"https:\/\/www.dentaltools.com.mx\/\">instrumentos dentales <\/a>contaminados exponen a los pacientes a peligrosos pat\u00f3genos.<\/p>\n<p>En las tres \u00faltimas d\u00e9cadas, se descubri\u00f3 saliva y sangre en los mecanismos internos de las piezas de mano de alta y baja velocidad y se propuso un nuevo est\u00e1ndar industrial para fabricar estos instrumentos con materiales que permiten su esterilizaci\u00f3n mediante vapor a presi\u00f3n.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.odontologos.mx\/noticias\/noticias\/nota-interna-esterelizarpieza-1.jpg\" \/><\/p>\n<p>Sin embargo, en muchos pa\u00edses los dentistas no cumplen con la esterilizaci\u00f3n obligatoria de la <a href=\"https:\/\/www.dentaltools.com.mx\/category-2-b0-Piezas-de-Mano-Dentales.html\">pieza de mano<\/a>, algo necesario para el ejercicio una odontolog\u00eda segura.<\/p>\n<p>Aunque las autoridades gubernamentales de salud publican y actualizan normas para la prevenci\u00f3n y el control de las enfermedades bucales, no vigilan el cumplimiento de la normativa y permiten la comercializaci\u00f3n de piezas de mano no esterilizables.<\/p>\n<p>Pocas facultades de odontolog\u00eda instruyen a sus alumnos sobre la selecci\u00f3n, compra y uso de piezas de mano esterilizables, los procedimientos de esterilizaci\u00f3n y mantenimiento. La mayor\u00eda no obligan a esterilizar la pieza de mano entre pacientes, aun cuando casi todas tienen centros de esterilizaci\u00f3n equipados con vapor a presi\u00f3n.<\/p>\n<p>En ausencia de una pol\u00edtica para la seguridad de los pacientes en las cl\u00ednicas de ense\u00f1anza, los estudiantes de odontolog\u00eda continuar\u00e1n adquiriendo los instrumentos m\u00e1s econ\u00f3micos, aun cuando no puedan ser esterilizados.<\/p>\n<p>La raz\u00f3n para no esterilizar la pieza de mano es de \u00edndole tecnol\u00f3gica. Las <a href=\"http:\/\/www.dentaldeal.es\/category-116-b0-Turbina-Pieza-de-Mano.html\">piezas de mano de alta velocidad<\/a>, impulsadas por aire y refrigeradas con agua, salieron a la venta a mediados del siglo pasado y durante cuarenta a\u00f1os su tecnolog\u00eda y materiales cambiaron poco. Muchos dentistas aprendimos a trabajar con versiones primitivas de estos instrumentos y nunca pensamos en esterilizarlas, pues sus componentes no resist\u00edan al calor. Adem\u00e1s, no era com\u00fan tener autoclaves en los consultorios dentales.<\/p>\n<p><strong>Momento de actuar<\/strong><br \/>\nLas agrupaciones gremiales deben jugar un importante papel para incrementar el cumplimiento de la esterilizaci\u00f3n de las piezas de mano.<\/p>\n<p>Los fabricantes y sus distribuidores deben vender \u00fanicamente piezas de mano que puedan ser esterilizadas. Igualmente importante es que ofrezcan los lubricantes, refacciones y el plan de mantenimiento que requieren.<\/p>\n<p>Las piezas de mano no pueden ser desinfectadas porque los desinfectantes son corrosivos y las destruyen. Adem\u00e1s, la geometr\u00eda interna, los empaques y el lubricante son barreras para la penetraci\u00f3n de cualquier desinfectante.<\/p>\n<p>El impacto econ\u00f3mico de ofrecer atenci\u00f3n segura a sus pacientes es tambi\u00e9n motivo de inquietud para el dentista. Una preocupaci\u00f3n similar existe en los servicios de endoscop\u00eda, ya que los endoscopios no se pueden esterilizar por calor y cuestan alrededor de $20,000 USD cada uno. La tecnolog\u00eda de baja temperatura para esterilizar endoscopios por plasma ionizante cuesta m\u00e1s de $100 USD por cada ciclo de esterilizaci\u00f3n, y el otro m\u00e9todo, el ciclo de gas de \u00f3xido de etileno, dura varias horas. Un hospital p\u00fablico en Am\u00e9rica Latina puede atender a 30 pacientes con media docena de endoscopios en ocho horas. La demanda del servicio presiona al personal para lavar y desinfectar cada instrumento lo m\u00e1s r\u00e1pido posible. No es sorprendente que en los procedimientos de endoscop\u00eda se documente el mayor n\u00famero de infecciones transmitidas de un paciente a otro por instrumental contaminado.<\/p>\n<p>Muchos dentistas err\u00f3neamente argumentan que &#8220;no pasa nada&#8221; por no apegarse a las recomendaciones del control de infecciones. Pero, los an\u00e1lisis gen\u00f3micos han documentado casos de pacientes afectados por la transmisi\u00f3n de hepatitis viral en cl\u00ednicas dentales.<\/p>\n<p>El paciente espera y merece ser atendido con instrumental est\u00e9ril debidamente procesado: jam\u00e1s nos otorgar\u00eda su consentimiento para ser atendido a sabiendas de que un instrumento contiene sangre y saliva de otros pacientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los mayores expertos internacionales en seguridad del paciente y control de infecciones asegura convincentemente que no esterilizar la pieza de mano es una conducta de alto riesgo para la salud de nuestros pacientes y para nuestra carrera profesional. Las autoridades sanitarias, las instituciones acad\u00e9micas y muchos dentistas han pasado por alto durante a\u00f1os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-214","post","type-post","status-publish","format-standard","hentry","category-autoclaves"],"_links":{"self":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts\/214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/comments?post=214"}],"version-history":[{"count":3,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts\/214\/revisions"}],"predecessor-version":[{"id":217,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/posts\/214\/revisions\/217"}],"wp:attachment":[{"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/media?parent=214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/categories?post=214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mydentalmexico.com\/index.php\/wp-json\/wp\/v2\/tags?post=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}